{"id":4058,"date":"2019-01-15T18:46:49","date_gmt":"2019-01-15T23:46:49","guid":{"rendered":"http:\/\/xperto-hypotheque-victor-hugo.ca\/interactive-form\/renovation\/"},"modified":"2023-01-13T11:03:48","modified_gmt":"2023-01-13T16:03:48","slug":"renewal","status":"publish","type":"page","link":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/interactive-form\/renewal\/","title":{"rendered":"Renewal"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-4058\" data-postid=\"4058\" class=\"themify_builder_content themify_builder_content-4058 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_psxg101 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_8xhz101 first\">\n                    <!-- module plain text -->\n<div  class=\"module module-plain-text tb_4j6l102 \" data-lazy=\"1\">\n        <div class=\"tb_text_wrap\">\n    <div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-4004\"><form id=\"wpforms-form-4004\" class=\"wpforms-validate wpforms-form\" data-formid=\"4004\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/4058\" data-token=\"78090d0aa9b6a6fe3bccb57b32125df9\" data-token-time=\"1778681622\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#ff9d00\" data-scroll=\"1\"><span class=\"wpforms-page-indicator-page-title\" data-page-3-title=\"Inform yourself\" data-page-5-title=\"Last step...\"><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 5<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:20%;background-color:#ff9d00\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-4004-field_9-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"9\"><\/div><div id=\"wpforms-4004-field_28-container\" class=\"wpforms-field wpforms-field-radio fi-section-title wpforms-list-2-columns\" data-field-id=\"28\"><label class=\"wpforms-field-label\">When do you plan to renew your mortgage? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-4004-field_28\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_28_1\" name=\"wpforms[fields][28]\" value=\"Right now\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_28_1\">Right now<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_28_2\" name=\"wpforms[fields][28]\" value=\"In 1-3 months\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_28_2\">In 1-3 months<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_28_3\" name=\"wpforms[fields][28]\" value=\"In 3-6 months\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_28_3\">In 3-6 months<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_28_4\" name=\"wpforms[fields][28]\" value=\"In 6-12 months\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_28_4\">In 6-12 months<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_28_5\" name=\"wpforms[fields][28]\" value=\"In a year or more\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_28_5\">In a year or more<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_28_6\" name=\"wpforms[fields][28]\" value=\"I do not know\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_28_6\">I do not know<\/label><\/li><\/ul><\/div><div id=\"wpforms-4004-field_53-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"53\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"1\" data-formid=\"4004\" disabled>NEXT<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-4004-field_29-container\" class=\"wpforms-field wpforms-field-radio fi-section-title wpforms-list-3-columns\" data-field-id=\"29\"><label class=\"wpforms-field-label\">Do you currently have mortgage insurance? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-4004-field_29\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_29_1\" name=\"wpforms[fields][29]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_29_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_29_2\" name=\"wpforms[fields][29]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_29_2\">No<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_29_3\" name=\"wpforms[fields][29]\" value=\"I do not know\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_29_3\">I do not know<\/label><\/li><\/ul><\/div><div id=\"wpforms-4004-field_12-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"12\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev\" data-action=\"prev\" data-page=\"2\" data-formid=\"4004\" disabled>BACK<\/button><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"2\" data-formid=\"4004\" disabled>NEXT<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3  \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-4004-field_56-container\" class=\"wpforms-field wpforms-field-radio fi-section-title wpforms-list-2-columns wpforms-conditional-trigger\" data-field-id=\"56\"><label class=\"wpforms-field-label\">Would you like to compare insurance products to see if you pay too much?<\/label><ul id=\"wpforms-4004-field_56\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_56_1\" name=\"wpforms[fields][56]\" value=\"Yes please\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_56_1\">Yes please<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_56_2\" name=\"wpforms[fields][56]\" value=\"No thank you\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_56_2\">No thank you<\/label><\/li><\/ul><\/div><div id=\"wpforms-4004-field_57-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"57\" style=\"display:none;\"><input type=\"text\" id=\"wpforms-4004-field_57\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][57]\" placeholder=\"Age\" required><\/div><div id=\"wpforms-4004-field_58-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-third wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"58\" style=\"display:none;\"><ul id=\"wpforms-4004-field_58\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_58_1\" name=\"wpforms[fields][58]\" value=\"Female\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_58_1\">Female<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_58_2\" name=\"wpforms[fields][58]\" value=\"Male\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_58_2\">Male<\/label><\/li><\/ul><\/div><div id=\"wpforms-4004-field_59-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"59\" style=\"display:none;\"><ul id=\"wpforms-4004-field_59\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4004-field_59_1\" name=\"wpforms[fields][59][]\" value=\"Smoker\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_59_1\">Smoker<\/label><\/li><\/ul><\/div><div id=\"wpforms-4004-field_60-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"60\" style=\"display:none;\"><div id=\"wpforms-4004-field_60\"><p>Co-Borrower (Optional)<\/p><\/div><\/div><div id=\"wpforms-4004-field_61-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"61\" style=\"display:none;\"><input type=\"text\" id=\"wpforms-4004-field_61\" class=\"wpforms-field-large\" name=\"wpforms[fields][61]\" placeholder=\"First and last name\" ><\/div><div id=\"wpforms-4004-field_62-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"62\" style=\"display:none;\"><input type=\"text\" id=\"wpforms-4004-field_62\" class=\"wpforms-field-large\" name=\"wpforms[fields][62]\" placeholder=\"Age\" ><\/div><div id=\"wpforms-4004-field_63-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-first wpforms-list-2-columns wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"63\" style=\"display:none;\"><ul id=\"wpforms-4004-field_63\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_63_1\" name=\"wpforms[fields][63]\" value=\"Female\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_63_1\">Female<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-4004-field_63_2\" name=\"wpforms[fields][63]\" value=\"Male\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_63_2\">Male<\/label><\/li><\/ul><\/div><div id=\"wpforms-4004-field_64-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-half wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"64\" style=\"display:none;\"><ul id=\"wpforms-4004-field_64\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4004-field_64_1\" name=\"wpforms[fields][64][]\" value=\"Smoker\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4004-field_64_1\">Smoker<\/label><\/li><\/ul><\/div><div id=\"wpforms-4004-field_55-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"55\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev\" data-action=\"prev\" data-page=\"3\" data-formid=\"4004\" disabled>BACK<\/button><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"3\" data-formid=\"4004\" disabled>NEXT<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-4  \" data-page=\"4\" style=\"display:none;\"><div id=\"wpforms-4004-field_50-container\" class=\"wpforms-field wpforms-field-divider fi-section-title\" data-field-id=\"50\"><h3 id=\"wpforms-4004-field_50\">Let us know any other relevant details about your project, so that we can help you get the best mortgage loan.<\/h3><\/div><div id=\"wpforms-4004-field_41-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"41\"><textarea id=\"wpforms-4004-field_41\" class=\"wpforms-field-large\" name=\"wpforms[fields][41]\" placeholder=\"Write the details here\" ><\/textarea><\/div><div id=\"wpforms-4004-field_19-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"19\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev\" data-action=\"prev\" data-page=\"4\" data-formid=\"4004\" disabled>BACK<\/button><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"4\" data-formid=\"4004\" disabled>NEXT<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-5 last \" data-page=\"5\" style=\"display:none;\"><div id=\"wpforms-4004-field_49-container\" class=\"wpforms-field wpforms-field-divider fi-section-title\" data-field-id=\"49\"><h3 id=\"wpforms-4004-field_49\">Last step! Your information is necessary to complete your request!<\/h3><\/div><div id=\"wpforms-4004-field_20-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"20\"><input type=\"text\" id=\"wpforms-4004-field_20\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][20]\" placeholder=\"Last name *\" required><\/div><div id=\"wpforms-4004-field_21-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"21\"><input type=\"text\" id=\"wpforms-4004-field_21\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][21]\" placeholder=\"First name *\" required><\/div><div id=\"wpforms-4004-field_22-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"22\"><input type=\"text\" id=\"wpforms-4004-field_22\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][22]\" placeholder=\"Phone number *\" required><\/div><div id=\"wpforms-4004-field_23-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"23\"><input type=\"text\" id=\"wpforms-4004-field_23\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][23]\" placeholder=\"Email\" required><\/div><div id=\"wpforms-4004-field_24-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"24\"><input type=\"text\" id=\"wpforms-4004-field_24\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][24]\" placeholder=\"Postal code *\" required><\/div><div id=\"wpforms-4004-field_25-container\" class=\"wpforms-field wpforms-field-select wpforms-one-half wpforms-field-select-style-classic\" data-field-id=\"25\"><select id=\"wpforms-4004-field_25\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][25]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Your region *<\/option><option value=\"\u00cele de Montr\u00e9al\"  class=\"choice-1 depth-1\"  >\u00cele de Montr\u00e9al<\/option><option value=\"Laval\"  class=\"choice-2 depth-1\"  >Laval<\/option><option value=\"Rive Sud de Montr\u00e9al\"  class=\"choice-3 depth-1\"  >Rive Sud de Montr\u00e9al<\/option><option value=\"Rive Nord de Montr\u00e9al\"  class=\"choice-4 depth-1\"  >Rive Nord de Montr\u00e9al<\/option><option value=\"Ville de Qu\u00e9bec\"  class=\"choice-5 depth-1\"  >Ville de Qu\u00e9bec<\/option><option value=\"Qu\u00e9bec Rive-Sud (L\u00e9vis)\"  class=\"choice-6 depth-1\"  >Qu\u00e9bec Rive-Sud (L\u00e9vis)<\/option><option value=\"Drummondville\"  class=\"choice-7 depth-1\"  >Drummondville<\/option><option value=\"Gatineau\"  class=\"choice-8 depth-1\"  >Gatineau<\/option><option value=\"Saguenay\"  class=\"choice-9 depth-1\"  >Saguenay<\/option><option value=\"Lac Saint-Jean\"  class=\"choice-10 depth-1\"  >Lac Saint-Jean<\/option><option value=\"Sherbrooke\"  class=\"choice-11 depth-1\"  >Sherbrooke<\/option><option value=\"Trois-Rivi\u00e8res\"  class=\"choice-12 depth-1\"  >Trois-Rivi\u00e8res<\/option><option value=\"Victoriaville\"  class=\"choice-13 depth-1\"  >Victoriaville<\/option><option value=\"Autres\"  class=\"choice-14 depth-1\"  >Autres<\/option><\/select><\/div><div id=\"wpforms-4004-field_10-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"10\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev\" data-action=\"prev\" data-page=\"5\" data-formid=\"4004\" disabled>BACK<\/button><\/div><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-4004-field-hp\" class=\"wpforms-field-label\">Phone<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-4004-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"4004\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/pages\/4058\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-4004\" class=\"wpforms-submit\" data-alt-text=\"SENDING...\" data-submit-text=\"GET MY FREE MORTGAGE OFFERS\" aria-live=\"assertive\" value=\"wpforms-submit\">GET MY FREE MORTGAGE OFFERS<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->    <\/div>\n<\/div>\n<!-- \/module plain text -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":4013,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4058","page","type-page","status-publish","hentry","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"aioseo_notices":[],"builder_content":"[wpforms id=\"4004\" title=\"false\"]","_links":{"self":[{"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/pages\/4058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/comments?post=4058"}],"version-history":[{"count":8,"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/pages\/4058\/revisions"}],"predecessor-version":[{"id":7844,"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/pages\/4058\/revisions\/7844"}],"up":[{"embeddable":true,"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/pages\/4013"}],"wp:attachment":[{"href":"https:\/\/xperto-hypotheque-victor-hugo.ca\/en\/wp-json\/wp\/v2\/media?parent=4058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}